﻿{"id":2347,"date":"2020-06-27T13:33:35","date_gmt":"2020-06-27T12:33:35","guid":{"rendered":"https:\/\/www.claudiawessling.de\/index.php\/home-english\/"},"modified":"2024-04-13T15:21:00","modified_gmt":"2024-04-13T14:21:00","slug":"home-english","status":"publish","type":"page","link":"https:\/\/www.claudiawessling.de\/index.php\/en\/home-english\/","title":{"rendered":"Home &#8211; English"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2022\/02\/Logo-Lehrende.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"243\" height=\"142\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2022\/02\/Logo-Lehrende.jpg\" alt=\"Competences\" class=\"wp-image-2562\" style=\"width:150px\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2020\/04\/SG-Logo-klein-Foxit-Reader.png\"><img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"75\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2020\/04\/SG-Logo-klein-Foxit-Reader.png\" alt=\"SG Logo\" class=\"wp-image-2201\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2021\/10\/dvct-coach-zertifiziert_rgb-e1633370915224.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"135\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2021\/10\/dvct-coach-zertifiziert_rgb-e1633370915224.jpg\" alt=\"Zertifizierter DVCT-Coach\" class=\"wp-image-2519\" style=\"width:150px\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/dvct.logo_.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"165\" height=\"80\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/dvct.logo_.jpg\" alt=\"\" class=\"wp-image-1816\" style=\"width:150px\"\/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2023\/12\/175_Badge_Autorisierter_INQA_Coach.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"175\" height=\"214\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2023\/12\/175_Badge_Autorisierter_INQA_Coach.jpg\" alt=\"Badge Autorisierter INQA Coach\" class=\"wp-image-2707\" style=\"width:110px\"\/><\/a><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc.png\"><img loading=\"lazy\" decoding=\"async\" width=\"9216\" height=\"2711\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc.png\" alt=\"\" class=\"wp-image-2789\" style=\"width:228px;height:auto\" srcset=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc.png 9216w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc-300x88.png 300w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc-1024x301.png 1024w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc-768x226.png 768w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc-1536x452.png 1536w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/mj2nd8lc-2048x602.png 2048w\" sizes=\"auto, (max-width: 9216px) 100vw, 9216px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/Logo_KoStelle_5cm.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"591\" height=\"217\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/Logo_KoStelle_5cm.jpg\" alt=\"\" class=\"wp-image-2790\" style=\"width:221px;height:auto\" srcset=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/Logo_KoStelle_5cm.jpg 591w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2024\/03\/Logo_KoStelle_5cm-300x110.jpg 300w\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n<table style=\"border: none;\">\n<tbody>\n<tr>\n<td colspan=\"2\">\n<\/p>\n\n<p>Welcome to my website!<\/p>\n<p>Every change, every departure towards something new is an exciting journey &#8211; whether for us as individuals or as an organization. I have been supporting these always personal and complex issues for 18 years now with care, a systemic approach and all my knowledge and experience. In other words: professionally, methodically and appropriate emotionally, because every development takes place in context and according to diverse dynamics.<\/p>\n<p>Continue to take care of yourselves and stay brave!\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<em>Claudia Wessling<\/em><span style=\"font-size: inherit; font-family: inherit; font-weight: inherit;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/span><em style=\"font-size: inherit; font-family: inherit; font-weight: inherit;\"><\/em><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td width=\"50%\">\n<h3>Individual solutions<\/h3>\n<p><div class='content-column one_half'><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1823 size-full\" src=\"http:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/Icon-Individuell.png\" alt=\"\" width=\"210\" height=\"208\" srcset=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/Icon-Individuell.png 210w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/Icon-Individuell-150x150.png 150w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><br \/><\/div><br \/><div class='content-column one_half last_column'><ul>\n<li>Clarification of professional &amp; conflictual issues<\/li>\n<li>Activate resources &amp; potentials<\/li>\n<li>Mastering decisions &amp; conflicts<\/li>\n<\/ul><\/div><div class='clear_column'><\/div><\/p>\n<\/td>\n<td width=\"50%\">\n<h3>Successful together<\/h3>\n<p><div class='content-column one_half'><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1824 size-full\" src=\"http:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/Icon-Gemeinsam.png\" alt=\"\" width=\"210\" height=\"208\" srcset=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/Icon-Gemeinsam.png 210w, https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/Icon-Gemeinsam-150x150.png 150w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><br \/><\/div><br \/><div class='content-column one_half last_column'><ul>\n<li>Strengthening through changes &amp; crises<\/li>\n<li>Organisational development, leadership &amp; change<\/li>\n<li>Cooperation &amp; work culture<\/li>\n<\/ul><\/div><div class='clear_column'><\/div><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Welcome to my website! Every change, every departure towards something new is an exciting journey &#8211; whether for us as individuals or as an organization. I have been supporting these always personal and complex issues for 18 years now with care, a systemic approach and all my knowledge and experience. In other words: professionally, methodically and appropriate emotionally, because every development takes place in context and according to diverse dynamics. Continue to take care of yourselves and stay brave!\u00a0 \u00a0<a class=\"more-link\" href=\"https:\/\/www.claudiawessling.de\/index.php\/en\/home-english\/\" title=\"Home &#8211; English\"><span>Weiter lesen<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2347","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages\/2347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/comments?post=2347"}],"version-history":[{"count":24,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages\/2347\/revisions"}],"predecessor-version":[{"id":2818,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages\/2347\/revisions\/2818"}],"wp:attachment":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/media?parent=2347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}