﻿{"id":1343,"date":"2017-03-12T13:45:57","date_gmt":"2017-03-12T12:45:57","guid":{"rendered":"http:\/\/www.claudiawessling.de\/?page_id=1343"},"modified":"2022-03-26T19:30:23","modified_gmt":"2022-03-26T18:30:23","slug":"business-coaching","status":"publish","type":"page","link":"https:\/\/www.claudiawessling.de\/index.php\/meine-arbeit\/business-coaching\/","title":{"rendered":"F\u00fchrungskr\u00e4fte- &#038; Businesscoaching"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1722 size-full alignleft\" src=\"http:\/\/www.claudiawessling.de\/wp-content\/uploads\/2017\/07\/clean-up.gif\" alt=\"\" width=\"235\" height=\"180\" \/><\/p>\n<p><strong>Perspektiven erweitern<br \/>\n<\/strong><\/p>\n<p>Abstand zu sich selbst gewinnen ist nicht einfach, denn Sie haben sich immer dabei. In meinen Business Coachings verstehe ich mich als Ihr Sparring-Partner, gemeinsam arbeiten wir an Ihrem Anliegen. Ob es um notwendige Ver\u00e4nderungen, Entscheidungen oder Konflikte geht: Sie haben die Expertise und kennen Ihre St\u00e4rken. Ich unterst\u00fctze Sie dabei, vorhandene Ziele und Strategien aus verschiedenen Perspektiven zu betrachten und zu aktualisieren. Methoden und Techniken w\u00e4hle ich je nach Situation und mache dies f\u00fcr Sie im Prozess auch transparent, denn Sie stehen f\u00fcr mich im Mittelpunkt. Ganz wichtig ist mir, Ihre eigene L\u00f6sungskompetenz zu st\u00e4rken.<\/p>\n<p><strong>Neue Optionen entdecken<br \/>\n<\/strong><a href=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2022\/03\/CW.HP1_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2589 size-full alignright\" src=\"https:\/\/www.claudiawessling.de\/wp-content\/uploads\/2022\/03\/CW.HP1_.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p>Priorit\u00e4ten zu setzen wird einfacher, wenn aus der Visualisierung Ihrer pers\u00f6nlichen aktuellen Situation ein anderer \u00dcberblick entsteht. Daraus entwickeln sich meist neue Handlungsoptionen und ein anderes Verst\u00e4ndnis. Neue Reaktionsm\u00f6glichkeiten bieten Potenzial f\u00fcr positive Ver\u00e4nderungen in Kommunikation und Umgang miteinander. Coaching hilft, die eigene Selbstwirksamkeit zu erkennen und weiter zu entwickeln. Gehen Sie gest\u00e4rkt und reflektiert einen f\u00fcr Sie passenden Weg in der F\u00fchrungsrolle, in (inneren) Konflikten oder in Ihrem Leben. Ich stehe Ihnen mit meiner Aufmerksamkeit, meinem Wissen und selbst entwickelten Coachingtools gerne zur Seite.<\/p>\n<p><strong>Umfang und Ablauf<\/strong><\/p>\n<p>Da es sich um eine sehr pers\u00f6nliche Angelegenheit handelt, biete ich vorab ein telefonisches Informationsgespr\u00e4ch an. Terminvereinbarung per E-Mail unter info@claudiawessling.de oder telefonisch unter 0160-94600191.<\/p>\n<p>Jedes Anliegen ist anders und verdient entsprechende W\u00fcrdigung. Um Ihnen eine Vorstellung des Umfangs zu geben: im Verlauf von 2-5 Sitzungen (jeweils 100 Minuten) k\u00f6nnen Themen gezielt bearbeitet werden. Sollte erneut Bedarf bestehen, sind Sie nat\u00fcrlich herzlich willkommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perspektiven erweitern Abstand zu sich selbst gewinnen ist nicht einfach, denn Sie haben sich immer dabei. In meinen Business Coachings verstehe ich mich als Ihr Sparring-Partner, gemeinsam arbeiten wir an Ihrem Anliegen. Ob es um notwendige Ver\u00e4nderungen, Entscheidungen oder Konflikte geht: Sie haben die Expertise und kennen Ihre St\u00e4rken. Ich unterst\u00fctze Sie dabei, vorhandene Ziele und Strategien aus verschiedenen Perspektiven zu betrachten und zu aktualisieren. Methoden und Techniken w\u00e4hle ich je nach Situation und mache dies f\u00fcr Sie im Prozess<a class=\"more-link\" href=\"https:\/\/www.claudiawessling.de\/index.php\/meine-arbeit\/business-coaching\/\" title=\"F\u00fchrungskr\u00e4fte- &#038; Businesscoaching\"><span>Weiter lesen<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":18,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1343","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages\/1343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/comments?post=1343"}],"version-history":[{"count":25,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages\/1343\/revisions"}],"predecessor-version":[{"id":2613,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages\/1343\/revisions\/2613"}],"up":[{"embeddable":true,"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/pages\/18"}],"wp:attachment":[{"href":"https:\/\/www.claudiawessling.de\/index.php\/wp-json\/wp\/v2\/media?parent=1343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}